{"id":2717,"date":"2017-08-30T14:51:00","date_gmt":"2017-08-30T12:51:00","guid":{"rendered":"https:\/\/21-grad.vaillant.de\/?p=2717"},"modified":"2019-05-09T15:42:06","modified_gmt":"2019-05-09T13:42:06","slug":"green-events-nachhaltigkeit-bei-grossveranstaltungen","status":"publish","type":"post","link":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/","title":{"rendered":"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen"},"content":{"rendered":"<p>Von Gro\u00dfveranstaltungen ist die Rede, wenn mehr als 10.000 Besucher oder 5.000 Aktive daran teilnehmen. Sportevents stellen dabei die Mehrzahl. In Deutschland gibt es jedes Jahr \u00fcber 150 sportliche Mega-Events, die insgesamt \u00fcber 25 Millionen Besucher anziehen. Darin sind die regelm\u00e4\u00dfigen Ligaspiele noch gar nicht eingerechnet. Hinzu kommen internationale Messen, Festivals, Konzerte, Paraden und regionale Feste wie das Oktoberfest oder Karneval. Events sind beliebt, denn sie bieten Austausch, Kultur, Information und machen nat\u00fcrlich auch viel Freude.<\/p>\n<p>Die Kehrseite solcher Veranstaltungen ist die mangelnde Umweltvertr\u00e4glichkeit. Allein die An- und Abreise der Teilnehmer f\u00fchrt zu einem enormen CO2-Aussto\u00df. Der Betrieb verursacht in der Regel einen erheblichen Mehrverbrauch an Energie und Wasser. Von den M\u00fcllbergen, die in erster Linie durch <a href=\"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/alternative-verpackungen\/\">Verpackungen<\/a> entstehen, ganz zu schweigen. Das Problem ist mittlerweile erkannt. Sowohl bei Besuchern als auch bei den Veranstaltern findet seit einigen Jahren ein Umdenken statt. Das Thema Nachhaltigkeit r\u00fcckt bei der Organisation von Events in den Fokus.<\/p>\n<h2><strong>Was macht Events gr\u00fcn?<\/strong><\/h2>\n<p>Nat\u00fcrlich hat Nachhaltigkeit in erster Linie viel mit Umweltschutz zu tun. Aber ein umfassendes Nachhaltigkeitskonzept f\u00fcr eine Veranstaltung geht weit dar\u00fcber hinaus. Es umfasst nicht nur \u00f6kologische, sondern auch \u00f6konomische und soziale Aspekte. Der Ma\u00dfnahmenkatalog eines echten Green Events enth\u00e4lt viele Punkte:<\/p>\n<div class=\"infobox default\"><\/p>\n<p><strong>Abfall:<\/strong> So wenig M\u00fcll wie m\u00f6glich produzieren. Vorhandenen M\u00fcll trennen und recyceln.<\/p>\n<p><strong>Mehrweg:<\/strong> Geschirr und andere Gebrauchsgegenst\u00e4nde sollten eingesammelt und mehrfach verwendet werden.<\/p>\n<p><strong>Catering:<\/strong> Regionale und saisonale Produkte einsetzen. Am besten Lebensmittel mit Fair Trade- und Biosiegel.<\/p>\n<p><strong>Mobilit\u00e4t:<\/strong> Die Nutzung von \u00d6PNV und Fahrrad sollte gef\u00f6rdert, Autoverkehr reduziert werden. Das gilt f\u00fcr Teilnehmer und Besucher.<\/p>\n<p><strong>Ressourcen:<\/strong> Die Veranstaltung sollte so ressourcenschonend wie m\u00f6glich sein. Wasser und Energie k\u00f6nnen mit entsprechenden Techniken geschont werden.<\/p>\n<p><strong>Soziale Verantwortung:<\/strong> Hierzu geh\u00f6ren verschiedene Ma\u00dfnahmen wie L\u00e4rmreduktion, Barrierefreiheit und faire Arbeitsbedingungen.<\/p>\n<p><\/div>\n<p>Zudem suchen nachhaltige Events aktiv den Austausch mit Anwohnern und regionalen Initiativen, damit der Veranstaltungsort so wenig wie m\u00f6glich belastet wird.<\/p>\n<h2><strong>Festivals: B\u00fchne frei f\u00fcr Umweltschutz<\/strong><\/h2>\n<p><a href=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/audience-1867754_1920.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2723 size-medium alignleft\" src=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/audience-1867754_1920-348x232.jpg\" alt=\"\" width=\"348\" height=\"232\" srcset=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/audience-1867754_1920-348x232.jpg 348w, https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/audience-1867754_1920-768x512.jpg 768w, https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/audience-1867754_1920-720x480.jpg 720w, https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/audience-1867754_1920.jpg 1920w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/a>Bei vielen gro\u00dfen Musikfestivals hat bereits ein Umdenken stattgefunden. Schlie\u00dflich ist die Belastung durch die Besucherscharen enorm:<\/p>\n<p><em>Im Durchschnitt f\u00e4llt auf einem Festivalwochenende mit etwa 80.000 Besuchern so viel M\u00fcll an, wie eine Kleinstadt der gleichen Einwohnerzahl pro Jahr verursacht!<\/em><\/p>\n<p>Festivals haben in der Regel sogenannte \u201eGreen Policies\u201c, in denen die Teilnehmer zu umweltbewusstem Verhalten aufgerufen werden. Mehrwegbecher und recyclingf\u00e4hige PET-Flaschen sind auf den meisten Musikveranstaltungen sowieso bereits Standard.<\/p>\n<p>Das Thema M\u00fcll ist auch auf dem englischen Glastonbury-Festival, das mit 170.000 Besuchern zu einem der weltweit Gr\u00f6\u00dften geh\u00f6rt, ein wichtiges Thema. 1.300 Freiwillige k\u00fcmmern sich ausschlie\u00dflich um Recycling. So konnte bereits mehr als die H\u00e4lfte des gesamten M\u00fclls recycelt werden. Der Anteil soll noch steigen. Auf dem Festivalgel\u00e4nde wurde zudem die gr\u00f6\u00dfte Solaranlage des Landes installiert. Die 1.500 qm-gro\u00dfen Panels versorgen einen Gro\u00dfteil der B\u00fchnen und St\u00e4nde mit \u00d6kostrom. Hinzu kommen viele Einzelma\u00dfnahmen, die insgesamt zu einem wirkungsvollen Nachhaltigkeitskonzept f\u00fchren:<\/p>\n<ul>\n<li>Kaffee- und Kakaogetr\u00e4nke tragen das Fair Trade-Label.<\/li>\n<li>J\u00e4hrlich kommen mehr als 1.200 Komposttoiletten zum Einsatz.<\/li>\n<li>Pappteller und Holzbesteck aus FSC-zertifizierten Materialien verbessern die \u00d6kobilanz.<\/li>\n<li>Informationsmaterial wird in Jutetaschen statt Plastikt\u00fcten ausgeteilt.<\/li>\n<\/ul>\n<p>Hinzu kommt, dass ein Gro\u00dfteil der Erl\u00f6se an gemeinn\u00fctzige Institutionen wie Oxfam, Greenpeace und WaterAid gespendet wird.<\/p>\n<h2><strong>Ein nachhaltiges Mega-Event: Das Oktoberfest <\/strong><\/h2>\n<p><a href=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/people-1284516_1920.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2722 size-medium\" src=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/people-1284516_1920-349x232.jpg\" alt=\"\" width=\"349\" height=\"232\" srcset=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/people-1284516_1920-349x232.jpg 349w, https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/people-1284516_1920-768x511.jpg 768w, https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/people-1284516_1920-722x480.jpg 722w, https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/people-1284516_1920.jpg 1920w\" sizes=\"auto, (max-width: 349px) 100vw, 349px\" \/><\/a>Auch das Oktoberfest wird seit \u00fcber zehn Jahren auf Basis eines Umweltkonzeptes organisiert. Aussteller m\u00fcssen sich f\u00fcr die lukrative Teilnahme auf einer der gr\u00f6\u00dften Veranstaltungen Deutschlands bewerben. Bei der Auswahl legen die Betreiber gro\u00dfen Wert auf \u00f6kologische Aspekte: Wird biologisch abbaubares Hydraulik\u00f6l verwendet? Wie schadstoffarm sind ben\u00f6tigte Zugmaschinen? Gibt es Anlagen f\u00fcr Wasser-Recycling oder eine Solaranlage? Zur Bewertung wird ein Punktesystem verwendet. Wer gr\u00fcn denkt, erh\u00e4lt eine hohe Punktzahl \u2013 und hat h\u00f6here Chancen dabei zu sein.<\/p>\n<p>Dadurch funktioniert Umweltbewusstsein auch im Kleinen. So erw\u00e4rmt ein Caf\u00e9 das Wasser zum H\u00e4ndewaschen mit einer Solaranlage auf dem Dach. Fahrgesch\u00e4fte verwenden energiesparende LEDs statt herk\u00f6mmlicher Gl\u00fchbirnen. Au\u00dferdem setzt man in der Gastronomie auf \u201eBio Schmankerl\u201c: Auf die Wiesn-Teller kommen vorwiegend regionale Spezialit\u00e4ten aus Betrieben, die gem\u00e4\u00df EG-\u00d6ko-Verordnung zertifiziert. Zutaten mit Biosiegel werden bevorzugt.<\/p>\n<div class=\"infobox default\"><\/p>\n<h2><strong>Tipp: Nachhaltige Meetings organisieren<\/strong><\/h2>\n<p>Nicht nur Mega-Events verursachen eine erh\u00f6hte Umweltbelastung. Auch \u00fcberschaubare Veranstaltungen und sogar einfache Meetings im B\u00fcro f\u00fchren beispielsweise zu mehr M\u00fcll. Machen Sie aus Ihrem n\u00e4chsten Kundentermin doch ein kleines Green Event:<\/p>\n<ul>\n<li>Stellen Sie statt Wasserflaschen Leitungswasser in Karaffen zur Verf\u00fcgung.<\/li>\n<li>Bieten Sie Fair Trade Kaffee an, nat\u00fcrlich nicht in Pappbechern.<\/li>\n<li>Verzichten Sie auf Notizbl\u00f6cke. Digitale Notizen sind effektive M\u00fcll-Killer.<\/li>\n<li>Buchen Sie R\u00e4ume mit viel Tageslicht \u2013 oder tagen Sie drau\u00dfen.<\/li>\n<li>Beauftragen Sie einen lokalen Anbieter f\u00fcr das Mittagessen und bestellen Sie Gerichte mit saisonalen Zutaten.<\/li>\n<li>Verwenden Sie wiederverwertbare Namensschilder.<\/li>\n<li>Nutzen Sie Projektoren statt Flipcharts.<\/li>\n<li>Ermuntern Sie alle Beteiligten, autofrei anzureisen, oder organisieren Sie Fahrgemeinschaften.<\/li>\n<li>Im Winter: Kleine R\u00e4ume nutzen, das spart Heizkosten.<\/li>\n<\/ul>\n<p><\/div>\n<p>F\u00fcr alle, die mehr zu dem Thema wissen m\u00f6chten, hat das Bundesumweltministerium einen <a href=\"http:\/\/www.bmub.bund.de\/themen\/wirtschaft-produkte-ressourcen-tourismus\/produkte-und-umwelt\/umweltfreundliche-beschaffung\/leitfaden-fuer-die-nachhaltige-organisation-von-veranstaltungen\/\">Leitfaden f\u00fcr die nachhaltige Organisation von Veranstaltungen<\/a> entwickelt. Diesen gibt es kostenlos zum Download.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festivals, Foren, Fu\u00dfball \u2013 Veranstaltungen ziehen sich durch das ganze Jahr und das weltweit. F\u00fcr die Teilnehmer haben sie einen gro\u00dfen Nutzen; man informiert oder am\u00fcsiert sich. Den Preis zahlt meist die Umwelt, denn besonders Gro\u00dfveranstaltungen verursachen eine massive \u00f6kologische Belastung. Nun gibt es einen vielversprechenden Gegentrend: Green Events.<\/p>\n","protected":false},"author":19,"featured_media":2724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[171,23],"coauthors":[243],"class_list":["post-2717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bewusst-und-sein","tag-lifestyle","tag-nachhaltigkeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen | 21 grad<\/title>\n<meta name=\"description\" content=\"Festivals &amp; Sportveranstaltungen machen Spa\u00df, aber auch viel Abfall \u2713 Wie k\u00f6nnen Gro\u00dfveranstaltungen nachhaltiger gestaltet werden? \u27a8 Erfahrt es hier!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen | 21 grad\" \/>\n<meta property=\"og:description\" content=\"Festivals &amp; Sportveranstaltungen machen Spa\u00df, aber auch viel Abfall \u2713 Wie k\u00f6nnen Gro\u00dfveranstaltungen nachhaltiger gestaltet werden? \u27a8 Erfahrt es hier!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/\" \/>\n<meta property=\"og:site_name\" content=\"21 grad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/21grad\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-30T12:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-09T13:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vaillant_de\" \/>\n<meta name=\"twitter:site\" content=\"@vaillant_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Tim\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/\"},\"author\":{\"name\":\"Tim\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/#\\\/schema\\\/person\\\/6c5f5a4071f0c7be145a9df11dac0709\"},\"headline\":\"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen\",\"datePublished\":\"2017-08-30T12:51:00+00:00\",\"dateModified\":\"2019-05-09T13:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/\"},\"wordCount\":881,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg\",\"keywords\":[\"Lifestyle\",\"Nachhaltigkeit\"],\"articleSection\":[\"Bewusst &amp; Sein\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/\",\"url\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/\",\"name\":\"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen | 21 grad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg\",\"datePublished\":\"2017-08-30T12:51:00+00:00\",\"dateModified\":\"2019-05-09T13:42:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/#\\\/schema\\\/person\\\/6c5f5a4071f0c7be145a9df11dac0709\"},\"description\":\"Festivals & Sportveranstaltungen machen Spa\u00df, aber auch viel Abfall \u2713 Wie k\u00f6nnen Gro\u00dfveranstaltungen nachhaltiger gestaltet werden? \u27a8 Erfahrt es hier!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg\",\"width\":940,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/bewusst-und-sein\\\/green-events-nachhaltigkeit-bei-grossveranstaltungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/#website\",\"url\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/\",\"name\":\"21 grad\",\"description\":\"Der Blog f\u00fcr Menschen, die weiterdenken\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/#\\\/schema\\\/person\\\/6c5f5a4071f0c7be145a9df11dac0709\",\"name\":\"Tim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20230516_Vaillant-Mitarbeitershooting-Lennep_0005_MKP-1-125x125.jpg9c05c6497faaba75d1eddfe0b2afcc63\",\"url\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20230516_Vaillant-Mitarbeitershooting-Lennep_0005_MKP-1-125x125.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20230516_Vaillant-Mitarbeitershooting-Lennep_0005_MKP-1-125x125.jpg\",\"caption\":\"Tim\"},\"description\":\"Ob Facebook oder Twitter, ob # oder @, ob Like oder Share \u2013 in meinem Arbeitsalltag dreht sich alles um Social Media. Ich sorge daf\u00fcr, dass unsere Zielgruppen sowohl informative als auch unterhaltsame und interaktive Inhalte mit Mehrwert auf unseren Kan\u00e4len finden. Nachhaltigkeit Nachhaltigkeit spielt vor allem in meiner Bewegung eine Rolle, da ich so viele Wege wie m\u00f6glich mit dem Rad zur\u00fccklege, u.a. den Weg zur Arbeit. Meiner Meinung nach wird viel zu oft auf das Auto zur\u00fcckgegriffen, vor allem f\u00fcr unn\u00f6tige Kurzstrecken unter 10 oder sogar weniger Minuten. Interessen Fu\u00dfball, Skifahren, Fitness, Unternehmungen in der Natur, Musik. Was w\u00fcrdest du mit auf eine einsame Insel nehmen? Einen Plattenspieler, ein gutes Buch und einen erfrischenden Drink. Wenn du eine Superkraft h\u00e4ttest, welche w\u00e4re das und warum? Ich w\u00fcrde mit meiner Superkraft gerne den Klimawandel aufhalten, da wir zwar viel reden, aber noch viel zu wenig daf\u00fcr tun.\",\"url\":\"https:\\\/\\\/www.vaillant.de\\\/21-grad\\\/autor\\\/tim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen | 21 grad","description":"Festivals & Sportveranstaltungen machen Spa\u00df, aber auch viel Abfall \u2713 Wie k\u00f6nnen Gro\u00dfveranstaltungen nachhaltiger gestaltet werden? \u27a8 Erfahrt es hier!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/","og_locale":"de_DE","og_type":"article","og_title":"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen | 21 grad","og_description":"Festivals & Sportveranstaltungen machen Spa\u00df, aber auch viel Abfall \u2713 Wie k\u00f6nnen Gro\u00dfveranstaltungen nachhaltiger gestaltet werden? \u27a8 Erfahrt es hier!","og_url":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/","og_site_name":"21 grad","article_publisher":"https:\/\/www.facebook.com\/21grad\/","article_published_time":"2017-08-30T12:51:00+00:00","article_modified_time":"2019-05-09T13:42:06+00:00","og_image":[{"width":940,"height":480,"url":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg","type":"image\/jpeg"}],"author":"Tim","twitter_card":"summary_large_image","twitter_creator":"@vaillant_de","twitter_site":"@vaillant_de","twitter_misc":{"Verfasst von":"Tim","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten","Written by":"Tim"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#article","isPartOf":{"@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/"},"author":{"name":"Tim","@id":"https:\/\/www.vaillant.de\/21-grad\/#\/schema\/person\/6c5f5a4071f0c7be145a9df11dac0709"},"headline":"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen","datePublished":"2017-08-30T12:51:00+00:00","dateModified":"2019-05-09T13:42:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/"},"wordCount":881,"commentCount":0,"image":{"@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg","keywords":["Lifestyle","Nachhaltigkeit"],"articleSection":["Bewusst &amp; Sein"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/","url":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/","name":"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen | 21 grad","isPartOf":{"@id":"https:\/\/www.vaillant.de\/21-grad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#primaryimage"},"image":{"@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg","datePublished":"2017-08-30T12:51:00+00:00","dateModified":"2019-05-09T13:42:06+00:00","author":{"@id":"https:\/\/www.vaillant.de\/21-grad\/#\/schema\/person\/6c5f5a4071f0c7be145a9df11dac0709"},"description":"Festivals & Sportveranstaltungen machen Spa\u00df, aber auch viel Abfall \u2713 Wie k\u00f6nnen Gro\u00dfveranstaltungen nachhaltiger gestaltet werden? \u27a8 Erfahrt es hier!","breadcrumb":{"@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#primaryimage","url":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg","contentUrl":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2017\/08\/Nachhaltige-Gro\u00dfveranstaltungen_header.jpg","width":940,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.vaillant.de\/21-grad\/bewusst-und-sein\/green-events-nachhaltigkeit-bei-grossveranstaltungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vaillant.de\/21-grad\/"},{"@type":"ListItem","position":2,"name":"Green Events: Nachhaltigkeit bei Gro\u00dfveranstaltungen"}]},{"@type":"WebSite","@id":"https:\/\/www.vaillant.de\/21-grad\/#website","url":"https:\/\/www.vaillant.de\/21-grad\/","name":"21 grad","description":"Der Blog f\u00fcr Menschen, die weiterdenken","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vaillant.de\/21-grad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.vaillant.de\/21-grad\/#\/schema\/person\/6c5f5a4071f0c7be145a9df11dac0709","name":"Tim","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2025\/04\/20230516_Vaillant-Mitarbeitershooting-Lennep_0005_MKP-1-125x125.jpg9c05c6497faaba75d1eddfe0b2afcc63","url":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2025\/04\/20230516_Vaillant-Mitarbeitershooting-Lennep_0005_MKP-1-125x125.jpg","contentUrl":"https:\/\/www.vaillant.de\/21-grad\/wp-content\/uploads\/2025\/04\/20230516_Vaillant-Mitarbeitershooting-Lennep_0005_MKP-1-125x125.jpg","caption":"Tim"},"description":"Ob Facebook oder Twitter, ob # oder @, ob Like oder Share \u2013 in meinem Arbeitsalltag dreht sich alles um Social Media. Ich sorge daf\u00fcr, dass unsere Zielgruppen sowohl informative als auch unterhaltsame und interaktive Inhalte mit Mehrwert auf unseren Kan\u00e4len finden. Nachhaltigkeit Nachhaltigkeit spielt vor allem in meiner Bewegung eine Rolle, da ich so viele Wege wie m\u00f6glich mit dem Rad zur\u00fccklege, u.a. den Weg zur Arbeit. Meiner Meinung nach wird viel zu oft auf das Auto zur\u00fcckgegriffen, vor allem f\u00fcr unn\u00f6tige Kurzstrecken unter 10 oder sogar weniger Minuten. Interessen Fu\u00dfball, Skifahren, Fitness, Unternehmungen in der Natur, Musik. Was w\u00fcrdest du mit auf eine einsame Insel nehmen? Einen Plattenspieler, ein gutes Buch und einen erfrischenden Drink. Wenn du eine Superkraft h\u00e4ttest, welche w\u00e4re das und warum? Ich w\u00fcrde mit meiner Superkraft gerne den Klimawandel aufhalten, da wir zwar viel reden, aber noch viel zu wenig daf\u00fcr tun.","url":"https:\/\/www.vaillant.de\/21-grad\/autor\/tim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/posts\/2717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/comments?post=2717"}],"version-history":[{"count":6,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/posts\/2717\/revisions"}],"predecessor-version":[{"id":4164,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/posts\/2717\/revisions\/4164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/media\/2724"}],"wp:attachment":[{"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/media?parent=2717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/categories?post=2717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/tags?post=2717"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.vaillant.de\/21-grad\/wp-json\/wp\/v2\/coauthors?post=2717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}